{"id":1619,"date":"2024-07-16T16:08:27","date_gmt":"2024-07-16T09:08:27","guid":{"rendered":"https:\/\/www.ductexcel.co.th\/?post_type=client&#038;p=1619"},"modified":"2024-07-16T16:08:31","modified_gmt":"2024-07-16T09:08:31","slug":"%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b8%88%e0%b8%b1%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b8%a4%e0%b8%9a","status":"publish","type":"client","link":"https:\/\/www.ductexcel.co.th\/th\/client\/%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b8%88%e0%b8%b1%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b8%a4%e0%b8%9a\/","title":{"rendered":"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e08\u0e31\u0e01\u0e23\u0e35\u0e19\u0e24\u0e1a\u0e14\u0e34\u0e19\u0e17\u0e23\u0e4c"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07 :<\/strong> \u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 :<\/strong> \u0e43\u0e0a\u0e49\u0e17\u0e48\u0e2d\u0e25\u0e21\u0e08\u0e32\u0e01 Duct Excel<\/p>\n","protected":false},"featured_media":499,"template":"","client-type":[25],"class_list":["post-1619","client","type-client","status-publish","has-post-thumbnail","hentry","client-type-flexible-duct"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e08\u0e31\u0e01\u0e23\u0e35\u0e19\u0e24\u0e1a\u0e14\u0e34\u0e19\u0e17\u0e23\u0e4c - Duct Excel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ductexcel.co.th\/th\/client\/\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e08\u0e31\u0e01\u0e23\u0e35\u0e19\u0e24\u0e1a\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e08\u0e31\u0e01\u0e23\u0e35\u0e19\u0e24\u0e1a\u0e14\u0e34\u0e19\u0e17\u0e23\u0e4c - Duct Excel\" \/>\n<meta property=\"og:description\" content=\"\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07 : \u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 : \u0e43\u0e0a\u0e49\u0e17\u0e48\u0e2d\u0e25\u0e21\u0e08\u0e32\u0e01 Duct Excel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ductexcel.co.th\/th\/client\/\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e08\u0e31\u0e01\u0e23\u0e35\u0e19\u0e24\u0e1a\/\" \/>\n<meta property=\"og:site_name\" content=\"Duct Excel\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-16T09:08:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ductexcel.co.th\/wp-content\/uploads\/2024\/05\/12-rama-hospital-bangplee.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"771\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ductexcel.co.th\/th\/client\/%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b8%88%e0%b8%b1%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b8%a4%e0%b8%9a\/\",\"url\":\"https:\/\/www.ductexcel.co.th\/th\/client\/%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b8%88%e0%b8%b1%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b8%a4%e0%b8%9a\/\",\"name\":\"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e08\u0e31\u0e01\u0e23\u0e35\u0e19\u0e24\u0e1a\u0e14\u0e34\u0e19\u0e17\u0e23\u0e4c - Duct Excel\",\"isPartOf\":{\"@id\":\"https:\/\/www.ductexcel.co.th\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ductexcel.co.th\/th\/client\/%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b8%88%e0%b8%b1%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b8%a4%e0%b8%9a\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ductexcel.co.th\/th\/client\/%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b8%88%e0%b8%b1%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b8%a4%e0%b8%9a\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ductexcel.co.th\/wp-content\/uploads\/2024\/05\/12-rama-hospital-bangplee.webp\",\"datePublished\":\"2024-07-16T09:08:27+00:00\",\"dateModified\":\"2024-07-16T09:08:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ductexcel.co.th\/th\/client\/%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b8%88%e0%b8%b1%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b8%a4%e0%b8%9a\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ductexcel.co.th\/th\/client\/%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b8%88%e0%b8%b1%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b8%a4%e0%b8%9a\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.ductexcel.co.th\/th\/client\/%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b8%88%e0%b8%b1%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b8%a4%e0%b8%9a\/#primaryimage\",\"url\":\"https:\/\/www.ductexcel.co.th\/wp-content\/uploads\/2024\/05\/12-rama-hospital-bangplee.webp\",\"contentUrl\":\"https:\/\/www.ductexcel.co.th\/wp-content\/uploads\/2024\/05\/12-rama-hospital-bangplee.webp\",\"width\":1080,\"height\":771},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ductexcel.co.th\/th\/client\/%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b8%88%e0%b8%b1%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b8%a4%e0%b8%9a\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ductexcel.co.th\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e08\u0e31\u0e01\u0e23\u0e35\u0e19\u0e24\u0e1a\u0e14\u0e34\u0e19\u0e17\u0e23\u0e4c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ductexcel.co.th\/#website\",\"url\":\"https:\/\/www.ductexcel.co.th\/\",\"name\":\"Duct Excel\",\"description\":\"\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e1c\u0e48\u0e19 PID | \u0e17\u0e48\u0e2d\u0e25\u0e21\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21\",\"publisher\":{\"@id\":\"https:\/\/www.ductexcel.co.th\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ductexcel.co.th\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ductexcel.co.th\/#organization\",\"name\":\"Duct Excel\",\"url\":\"https:\/\/www.ductexcel.co.th\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.ductexcel.co.th\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ductexcel.co.th\/wp-content\/uploads\/2024\/05\/ductexcel-logo.webp\",\"contentUrl\":\"https:\/\/www.ductexcel.co.th\/wp-content\/uploads\/2024\/05\/ductexcel-logo.webp\",\"width\":354,\"height\":230,\"caption\":\"Duct Excel\"},\"image\":{\"@id\":\"https:\/\/www.ductexcel.co.th\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e08\u0e31\u0e01\u0e23\u0e35\u0e19\u0e24\u0e1a\u0e14\u0e34\u0e19\u0e17\u0e23\u0e4c - Duct Excel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ductexcel.co.th\/th\/client\/\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e08\u0e31\u0e01\u0e23\u0e35\u0e19\u0e24\u0e1a\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e08\u0e31\u0e01\u0e23\u0e35\u0e19\u0e24\u0e1a\u0e14\u0e34\u0e19\u0e17\u0e23\u0e4c - Duct Excel","og_description":"\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07 : \u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 : \u0e43\u0e0a\u0e49\u0e17\u0e48\u0e2d\u0e25\u0e21\u0e08\u0e32\u0e01 Duct Excel","og_url":"https:\/\/www.ductexcel.co.th\/th\/client\/\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e08\u0e31\u0e01\u0e23\u0e35\u0e19\u0e24\u0e1a\/","og_site_name":"Duct Excel","article_modified_time":"2024-07-16T09:08:31+00:00","og_image":[{"width":1080,"height":771,"url":"https:\/\/www.ductexcel.co.th\/wp-content\/uploads\/2024\/05\/12-rama-hospital-bangplee.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ductexcel.co.th\/th\/client\/%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b8%88%e0%b8%b1%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b8%a4%e0%b8%9a\/","url":"https:\/\/www.ductexcel.co.th\/th\/client\/%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b8%88%e0%b8%b1%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b8%a4%e0%b8%9a\/","name":"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e08\u0e31\u0e01\u0e23\u0e35\u0e19\u0e24\u0e1a\u0e14\u0e34\u0e19\u0e17\u0e23\u0e4c - Duct Excel","isPartOf":{"@id":"https:\/\/www.ductexcel.co.th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ductexcel.co.th\/th\/client\/%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b8%88%e0%b8%b1%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b8%a4%e0%b8%9a\/#primaryimage"},"image":{"@id":"https:\/\/www.ductexcel.co.th\/th\/client\/%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b8%88%e0%b8%b1%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b8%a4%e0%b8%9a\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ductexcel.co.th\/wp-content\/uploads\/2024\/05\/12-rama-hospital-bangplee.webp","datePublished":"2024-07-16T09:08:27+00:00","dateModified":"2024-07-16T09:08:31+00:00","breadcrumb":{"@id":"https:\/\/www.ductexcel.co.th\/th\/client\/%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b8%88%e0%b8%b1%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b8%a4%e0%b8%9a\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ductexcel.co.th\/th\/client\/%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b8%88%e0%b8%b1%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b8%a4%e0%b8%9a\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.ductexcel.co.th\/th\/client\/%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b8%88%e0%b8%b1%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b8%a4%e0%b8%9a\/#primaryimage","url":"https:\/\/www.ductexcel.co.th\/wp-content\/uploads\/2024\/05\/12-rama-hospital-bangplee.webp","contentUrl":"https:\/\/www.ductexcel.co.th\/wp-content\/uploads\/2024\/05\/12-rama-hospital-bangplee.webp","width":1080,"height":771},{"@type":"BreadcrumbList","@id":"https:\/\/www.ductexcel.co.th\/th\/client\/%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a%e0%b8%b1%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b8%88%e0%b8%b1%e0%b8%81%e0%b8%a3%e0%b8%b5%e0%b8%99%e0%b8%a4%e0%b8%9a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ductexcel.co.th\/"},{"@type":"ListItem","position":2,"name":"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e08\u0e31\u0e01\u0e23\u0e35\u0e19\u0e24\u0e1a\u0e14\u0e34\u0e19\u0e17\u0e23\u0e4c"}]},{"@type":"WebSite","@id":"https:\/\/www.ductexcel.co.th\/#website","url":"https:\/\/www.ductexcel.co.th\/","name":"Duct Excel","description":"\u0e1c\u0e39\u0e49\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e41\u0e1c\u0e48\u0e19 PID | \u0e17\u0e48\u0e2d\u0e25\u0e21\u0e2d\u0e25\u0e39\u0e21\u0e34\u0e40\u0e19\u0e35\u0e22\u0e21","publisher":{"@id":"https:\/\/www.ductexcel.co.th\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ductexcel.co.th\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.ductexcel.co.th\/#organization","name":"Duct Excel","url":"https:\/\/www.ductexcel.co.th\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.ductexcel.co.th\/#\/schema\/logo\/image\/","url":"https:\/\/www.ductexcel.co.th\/wp-content\/uploads\/2024\/05\/ductexcel-logo.webp","contentUrl":"https:\/\/www.ductexcel.co.th\/wp-content\/uploads\/2024\/05\/ductexcel-logo.webp","width":354,"height":230,"caption":"Duct Excel"},"image":{"@id":"https:\/\/www.ductexcel.co.th\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.ductexcel.co.th\/th\/wp-json\/wp\/v2\/client\/1619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ductexcel.co.th\/th\/wp-json\/wp\/v2\/client"}],"about":[{"href":"https:\/\/www.ductexcel.co.th\/th\/wp-json\/wp\/v2\/types\/client"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ductexcel.co.th\/th\/wp-json\/wp\/v2\/media\/499"}],"wp:attachment":[{"href":"https:\/\/www.ductexcel.co.th\/th\/wp-json\/wp\/v2\/media?parent=1619"}],"wp:term":[{"taxonomy":"client-type","embeddable":true,"href":"https:\/\/www.ductexcel.co.th\/th\/wp-json\/wp\/v2\/client-type?post=1619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}